{"id":450,"date":"2019-10-23T10:05:16","date_gmt":"2019-10-23T10:05:16","guid":{"rendered":"http:\/\/www.jensliebchen.thepeople.world\/?page_id=450"},"modified":"2019-10-31T08:56:29","modified_gmt":"2019-10-31T08:56:29","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/jensliebchen.de\/de\/datenschutz\/","title":{"rendered":"datenschutz"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":13,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-450","page","type-page","status-publish","hentry"],"grid":"{\r\n  \"colCount\": 12,\r\n  \"colGutter\": 1,\r\n  \"rowGutters\": [],\r\n  \"frameMargin\": 5,\r\n  \"topFrameMargin\": 40,\r\n  \"bottomFrameMargin\": 5,\r\n  \"rowAttrs\": [\r\n    {}\r\n  ],\r\n  \"bgColor\": null,\r\n  \"cont\": [\r\n    {\r\n      \"type\": \"text\",\r\n      \"cont\": \"<p class=\\\"_about_current\\\">Mit dieser Datenschutzerkl\u00e4rung m\u00f6chten wir Sie dar\u00fcber informieren, wie wir personenbezogene Daten verarbeiten. Wir sind uns bewusst, welche Bedeutung die Verarbeitung personenbezogener Daten f\u00fcr den betroffenen Nutzer hat und beachten dementsprechend alle einschl\u00e4gigen gesetzlichen Vorgaben. Dabei ist der Schutz Ihrer Privatsph\u00e4re f\u00fcr uns von h\u00f6chster Bedeutung. Deshalb ist das Einhalten der gesetzlichen Bestimmungen zum Datenschutz f\u00fcr uns selbstverst\u00e4ndlich.<\/p><p class=\\\"_about_current\\\"><u>Kontakt<\/u><\/p><p class=\\\"_about_current\\\">Jens Liebchen \/ Studio<br \/>Freienwalder Str. 17<br \/>13055 Berlin<br \/>Germany<\/p><p class=\\\"_about_current\\\">contact (at) jensliebchen.de<\/p><p class=\\\"_about_current\\\"><u>Datenschutzbeauftragter<\/u><br \/>Sie erreichen unseren Datenschutzbeauftragten unter contact (at) jensliebchen.de<\/p><p class=\\\"_about_current\\\"><u>Erhobene Daten<\/u><br \/>Eine Nutzung der Internetseiten der \u201eJens Liebchen Photography\u201c ist grunds\u00e4tzlich ohne jede Angabe personenbezogener Daten m\u00f6glich. Beim Zugriff auf diese Webseiten \u00fcbermittelt der Browser des Besuchers automatisch Daten \u00fcber die gew\u00fcnschte Ressource, die IP-Adresse, an die die Daten \u00fcbermittelt werden sollen sowie gegebenenfalls auch spezifische Daten aus vorherigen Anfragen (Cookies, Referer, Formulare, etc.) an den Server unserer Website. Ein Teil dieser Daten wird automatisch geloggt, um den technischen Betrieb sicherstellen zu k\u00f6nnen. Diese Informationen werden tempor\u00e4r in einem sogenannten Logfile gespeichert.<br \/>Folgende Informationen werden dabei ohne Ihr Zutun erfasst und bis zur automatisierten L\u00f6schung gespeichert: IP-Adresse des anfragenden Rechners, Datum und Uhrzeit des Zugriffs, Name und URL der abgerufenen Datei, Website, von der aus der Zugriff erfolgt (Referrer-URL), verwendeter Browser und ggf. das Betriebssystem Ihres Rechners sowie der Name Ihres Access-Providers.<br \/>Die genannten Daten werden durch uns zu folgenden Zwecken verarbeitet: Gew\u00e4hrleistung eines reibungslosen Verbindungsaufbaus der Website, Gew\u00e4hrleistung einer komfortablen Nutzung unserer Website, Auswertung der Systemsicherheit und -stabilit\u00e4t sowie zu weiteren administrativen Zwecken.<br \/>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist Art.\u00a06 Abs.\u00a01 S.\u00a01 lit.\u00a0f DSGVO. Unser berechtigtes Interesse folgt aus oben aufgelisteten Zwecken zur Datenerhebung. In keinem Fall verwenden wir die erhobenen Daten zu dem Zweck, R\u00fcckschl\u00fcsse auf Ihre Person zu ziehen.<br \/>Sollten Sie uns per E-Mail oder Telefon oder \u00e4hnliches wegen eines Auftrags oder Angebots kontaktieren, so speichern wir :<br \/>- Kontaktinformationen<br \/>- Auftragsinformationen und -bedingungen<br \/>- ggfls. Zahlungsinformationen<\/p><p class=\\\"_about_current\\\"><u>Zweck<\/u><br \/>Wir verarbeiten Ihre Daten zu den folgenden Zwecken:<br \/>\u2013 Vertragsabwicklung<br \/>\u2013 Werbung<br \/>\u2013 Statistik<\/p><p class=\\\"_about_current\\\"><u>Rechtsgrundlage<\/u><br \/>Die Verarbeitung Ihrer Daten geschieht auf der folgenden Rechtsgrundlage:<br \/>\u2013 Ihre Einwilligung, Art. 6 Abs. 1 lit. a) DSGVO<br \/>\u2013 zur Durchf\u00fchrung eines Vertrags mit Ihnen und zur Erf\u00fcllung gesetzlicher Pflichten, Art. 6 Abs. 1 lit. b) DSGVO<br \/>\u2013 berechtigte Interessen, Art. 6 Abs. 1 lit. f) DSGVO (siehe unten)<\/p><p class=\\\"_about_current\\\"><u>Berechtigte Interessen<\/u><br \/>Bei der Verarbeitung Ihrer Daten verfolgen wir die folgenden berechtigten Interessen:<br \/>\u2013 Erstellung von Angeboten<br \/>\u2013 Auftragsabwicklung<br \/>\u2013 Schutz vor Missbrauch<br \/>\u2013 Statistik<\/p><p class=\\\"_about_current\\\"><u>Datenempf\u00e4nger<\/u><br \/>Bei der Verarbeitung Ihrer Daten arbeiten wir mit den folgenden Dienstleistern zusammen, die Zugriff auf Ihre Daten haben:<br \/>\u2013 Webhosting-Anbieter: NetBeat<br \/>\u2013 Versanddienstleister wie WeTransfer und Picdrop<br \/>\u2013 Anbieter von Webanalyse-Tools<\/p><p class=\\\"_about_current\\\"><u>Datenquellen<\/u><br \/>Wir erhalten die Daten von Ihnen (einschlie\u00dflich \u00fcber die von Ihnen verwendeten Ger\u00e4te).<\/p><p class=\\\"_about_current\\\"><u>Daten\u00fcbertragung in Drittl\u00e4nder<\/u><br \/>Es findet eine Daten\u00fcbertragung in Drittl\u00e4nder au\u00dferhalb der Europ\u00e4ischen Union statt. Dies erfolgt auf der Grundlage gesetzlich vorgesehener vertraglicher Regelungen, die einen angemessenen Schutz Ihrer Daten sicherstellen sollen und die Sie auf Anfrage einsehen k\u00f6nnen.<\/p><p class=\\\"_about_current\\\"><u>Weitergabe von Daten<\/u><br \/>Selbstverst\u00e4ndlich geben wir keine pers\u00f6nlichen Daten f\u00fcr Werbe- oder Marketingzwecke an Dritte weiter. Wir geben Ihre Daten nur dann an Dritte weiter, wenn dies f\u00fcr die Erbringung unserer Dienstleistung zwingend erforderlich ist. Eine \u00dcbermittlung Ihrer pers\u00f6nlichen Daten an Dritte zu anderen als den im Folgenden aufgef\u00fchrten Zwecken findet nicht statt.<br \/>Wir geben Ihre pers\u00f6nlichen Daten nur an Dritte weiter, wenn:<br \/>- Sie Ihre nach Art. 6 Abs. 1 S. 1 lit. a DSGVO ausdr\u00fcckliche Einwilligung dazu erteilt haben,<br \/>- die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. f DSGVO zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe Ihrer Daten haben,<br \/>- f\u00fcr den Fall, dass f\u00fcr die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. c DSGVO eine gesetzliche Verpflichtung besteht, sowie<br \/>- dies gesetzlich zul\u00e4ssig und nach Art. 6 Abs. 1 S. 1 lit. b DSGVO f\u00fcr die Abwicklung von Vertragsverh\u00e4ltnissen mit Ihnen erforderlich ist.<\/p><p class=\\\"_about_current\\\"><u>Speicherdauer<\/u><br \/>Wir speichern Ihre Daten,<br \/>\u2013 wenn Sie in die Verarbeitung eingewilligt haben h\u00f6chstens solange, bis Sie Ihre Einwilligung widerrufen,<br \/>\u2013 wenn wir die Daten zur Durchf\u00fchrung eines Vertrags oder zur Erf\u00fcllung gesetzlicher Pflichten ben\u00f6tigen h\u00f6chstens solange, wie das Vertragsverh\u00e4ltnis mit Ihnen besteht oder gesetzliche Aufbewahrungsfristen laufen,<br \/>\u2013 wenn wir die Daten auf der Grundlage eines berechtigten Interesses verwenden h\u00f6chstens solange, wie Ihr Interesse an einer L\u00f6schung oder Anonymisierung nicht \u00fcberwiegt.<\/p><p class=\\\"_about_current\\\"><u>Rechte des Betroffenen<\/u><br \/>Sie haben \u2013 teilweise unter bestimmten Voraussetzungen \u2013 das Recht,<br \/>\u2013 Auskunft \u00fcber die Verarbeitung Ihrer Daten zu verlangen,<br \/>\u2013 Ihre Daten zu berichtigen,<br \/>\u2013 Ihre Daten l\u00f6schen oder sperren zu lassen,<br \/>\u2013 die Verarbeitung einschr\u00e4nken zu lassen,<br \/>\u2013 der Verarbeitung Ihrer Daten zu widersprechen,<br \/>\u2013 Ihre Daten in einem \u00fcbertragbaren Format zu erhalten und einem Dritten zu \u00fcbermitteln,<br \/>\u2013 Ihre Einwilligung zur Verarbeitung Ihrer Daten f\u00fcr die Zukunft zu widerrufen und<br \/>\u2013 sich bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde \u00fcber eine unzul\u00e4ssige Datenverarbeitung zu beschweren.<\/p><p class=\\\"_about_current\\\"><u>Erfordernis oder Verpflichtung zur Bereitstellung von Daten<\/u><br \/>Soweit dies bei der Erhebung nicht ausdr\u00fccklich angegeben ist, ist die Bereitstellung von Daten nicht erforderlich oder verpflichtend.<\/p><p class=\\\"_about_current\\\">Stand dieser Datenschutzerkl\u00e4rung<br \/>25. Mai 2018<\/p><p class=\\\"_about_current\\\">Wir behalten uns vor, diese Datenschutzerkl\u00e4rung jederzeit mit Wirkung f\u00fcr die Zukunft zu \u00e4ndern.<\/p>\",\r\n      \"align\": \"middle\",\r\n      \"row\": 0,\r\n      \"col\": 3,\r\n      \"colspan\": 9,\r\n      \"offsetx\": 0,\r\n      \"offsety\": 0,\r\n      \"spaceabove\": 0,\r\n      \"spacebelow\": 0,\r\n      \"yvel\": 1,\r\n      \"push\": 3,\r\n      \"relid\": 4,\r\n      \"frameOverflow\": \"\"\r\n    }\r\n  ]\r\n}","phonegrid":"","_links":{"self":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages\/450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/comments?post=450"}],"version-history":[{"count":0,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages\/450\/revisions"}],"wp:attachment":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/media?parent=450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}