{"id":473,"date":"2019-10-23T16:34:16","date_gmt":"2019-10-21T13:44:03","guid":{"rendered":"http:\/\/www.jensliebchen.thepeople.world\/commissions_phone-2\/"},"modified":"2022-05-29T09:30:14","modified_gmt":"2022-05-29T09:30:14","slug":"art_books","status":"publish","type":"page","link":"https:\/\/jensliebchen.de\/de\/art_books\/","title":{"rendered":"Art\/books_phone"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-473","page","type-page","status-publish","hentry"],"grid":"{\"colCount\":12,\"colGutter\":1,\"rowGutters\":[5,5,5,5,5,5],\"frameMargin\":5,\"topFrameMargin\":40,\"bottomFrameMargin\":5,\"rowAttrs\":[[],[],[],[],[],[],[]],\"bgColor\":null,\"cont\":[{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"align\":\"middle\",\"row\":0,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":7,\"title\":\"L.A. Crossing\",\"postid\":631,\"descr\":\"\",\"link\":\"\\\/crossing\\\/\",\"attid\":1621,\"ar\":0.66666666666666662965923251249478198587894439697265625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01-265x177.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01-512x341.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01-768x512.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01-1024x683.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01-1280x853.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LA_Crossing_Jens_Liebchen_01.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"align\":\"middle\",\"row\":1,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":6,\"title\":\"Tsukuba - Narita\",\"postid\":596,\"descr\":\"\",\"link\":\"\\\/tsukuba-narita\\\/\",\"attid\":608,\"ar\":0.66666666666666662965923251249478198587894439697265625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28-265x177.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28-512x341.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28-768x512.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28-1024x683.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28-1280x853.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/05_02_tsukuba_narita_beam-28.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\",\"align\":\"top\",\"row\":2,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":4,\"title\":\"System\",\"postid\":318,\"descr\":\"\",\"link\":\"\\\/system\\\/\",\"attid\":430,\"ar\":0.66679999999999994830801597345271147787570953369140625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-265x177.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-512x341.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-768x512.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-1024x683.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-1280x854.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01-1920x1280.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-system-01.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"align\":\"top\",\"row\":3,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":8,\"title\":\"Playing Fields\",\"postid\":671,\"descr\":\"\",\"link\":\"\\\/playing_fields\\\/\",\"attid\":1376,\"ar\":0.66666666666666662965923251249478198587894439697265625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1-265x177.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1-512x341.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1-768x512.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1-1024x683.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1-1280x853.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-playing-fields-01-thumb-1.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"align\":\"top\",\"row\":4,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":9,\"title\":\"Politik & Kunst\",\"postid\":575,\"descr\":\"\",\"link\":\"\\\/politics-art\\\/\",\"attid\":576,\"ar\":0.65800000000000002930988785010413266718387603759765625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1-265x174.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1-512x337.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1-768x505.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1-1024x674.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1-1280x842.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-politics-art-1.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"align\":\"top\",\"row\":5,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":10,\"title\":\"DL07 Stereotypes of War\",\"postid\":527,\"descr\":\"\",\"link\":\"\\\/dl07\\\/\",\"attid\":1157,\"ar\":0.68000000000000004884981308350688777863979339599609375,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1-265x180.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1-512x348.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1-768x522.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1-1024x696.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1-1280x870.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/jens-liebchen-dl07-stereotypes-war-01-1.jpg\"},\"mo_sizes\":null,\"mo_h\":0,\"mo_w\":0,\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\"},{\"type\":\"postThumbnail\",\"cont\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"align\":\"middle\",\"row\":6,\"col\":0,\"colspan\":12,\"offsetx\":0,\"offsety\":0,\"spaceabove\":0,\"spacebelow\":0,\"yvel\":1,\"push\":0,\"relid\":5,\"title\":\"Books \\\/ Editions\",\"postid\":418,\"descr\":\"\",\"link\":\"\\\/books_editions\\\/\",\"attid\":1577,\"ar\":0.66666666666666662965923251249478198587894439697265625,\"sizes\":{\"_265\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1-265x177.jpg\",\"_512\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1-512x341.jpg\",\"_768\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1-768x512.jpg\",\"_1024\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1-1024x683.jpg\",\"_1280\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1-1280x853.jpg\",\"_1920\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"_2560\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"_3200\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"_3840\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"_4096\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\",\"full\":\"\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/LAC-BOOK-1.jpg\"},\"mo_sizes\":\"\",\"mo_h\":\"\",\"mo_w\":\"\",\"video_url\":\"\",\"video_w\":0,\"video_h\":0,\"frameOverflow\":\"\",\"w\":1800,\"h\":1200,\"tags\":[]}]}","phonegrid":"","_links":{"self":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages\/473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/comments?post=473"}],"version-history":[{"count":0,"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/pages\/473\/revisions"}],"wp:attachment":[{"href":"https:\/\/jensliebchen.de\/de\/wp-json\/wp\/v2\/media?parent=473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}